{"id":988,"date":"2009-12-07T13:10:02","date_gmt":"2009-12-07T12:10:02","guid":{"rendered":"http:\/\/www.gegenstrom.net\/wordpress\/?p=988"},"modified":"2009-12-07T13:10:02","modified_gmt":"2009-12-07T12:10:02","slug":"nichts-gelernt","status":"publish","type":"post","link":"https:\/\/www.gegenstrom.net\/wordpress\/2009\/12\/07\/nichts-gelernt\/","title":{"rendered":"Nichts gelernt"},"content":{"rendered":"<p>In einem Kommentar zur Gr\u00fcndung der &#8222;Bad Bank&#8220; f\u00fcr die WestLB schreibt &#8222;die tageszeitung&#8220; (26.11.2009):<\/p>\n<blockquote><p><em>Diesmal hatte der Staat keine Chance&#8230; denn die WestLB wird als systemrelevant eingestuft. Ihr Untergang k\u00f6nnte, wie seinerzeit der von Lehman Brothers, das ganze Finanzsystem mit &#8230; rei\u00dfen.<\/em><\/p>\n<p><em>Der Skandal liegt &#8230; in der Tatsache, dass es nach wie vor zahlreiche Banken gibt, die einfach zu gro\u00df sind, um sie pleitegehen zu lassen: too big to fail.<\/em><\/p>\n<p><em>Zur Hoffnung Anlass gibt nun ausgerechnet die EU &#8211; deren neoliberale Vorgaben einst die provinziell beh\u00e4bigen Landesbanken \u00fcberhaupt erst zu globalen Zockerinstituten mutieren lie\u00dfen. Wettbewerbskommissarin Neelie Kroes hat &#8230; das Problem erkannt. In den Niederlanden und Gro\u00dfbritannien sorgt sie daf\u00fcr, dass mit Staatsknete gerettete Banken so weit zusammengestutzt werden, dass sie wenigstens in Zukunft kein Risiko mehr &#8230; darstellen.<\/em><\/p>\n<p><em>Eine derartige Lernkurve zeichnet sich in Berlin nicht ab. Hier bem\u00fcht sich die Regierung nur feige weiter darum, es den Herren des Geldes auch ja recht zu machen.<br \/>\n<\/em><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>In einem Kommentar zur Gr\u00fcndung der &#8222;Bad Bank&#8220; f\u00fcr die WestLB schreibt &#8222;die tageszeitung&#8220; (26.11.2009): Diesmal hatte der Staat keine Chance&#8230; denn die WestLB wird als systemrelevant eingestuft. Ihr Untergang k\u00f6nnte, wie seinerzeit der von Lehman Brothers, das ganze Finanzsystem mit &#8230; rei\u00dfen. Der Skandal liegt &#8230; in der Tatsache, dass es nach wie vor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[525],"tags":[171,517,635],"class_list":["post-988","post","type-post","status-publish","format-standard","hentry","category-staatsversagen","tag-banken","tag-landesbanken","tag-west-lb"],"_links":{"self":[{"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/posts\/988"}],"collection":[{"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/comments?post=988"}],"version-history":[{"count":2,"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/posts\/988\/revisions"}],"predecessor-version":[{"id":990,"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/posts\/988\/revisions\/990"}],"wp:attachment":[{"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/media?parent=988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/categories?post=988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/tags?post=988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}