{"id":2068,"date":"2011-02-09T11:53:21","date_gmt":"2011-02-09T10:53:21","guid":{"rendered":"http:\/\/www.gegenstrom.net\/wordpress\/?p=2068"},"modified":"2011-02-09T11:53:21","modified_gmt":"2011-02-09T10:53:21","slug":"banken-wetten-vor-gericht","status":"publish","type":"post","link":"https:\/\/www.gegenstrom.net\/wordpress\/2011\/02\/09\/banken-wetten-vor-gericht\/","title":{"rendered":"Banken-Wetten vor Gericht"},"content":{"rendered":"<p>Zwei Unternehmer werfen der Deutschen Bank Falschberatung vor, die ihnen Zinsswaps als &#8222;gutes Produkt zur Zinsoptimierung&#8220; verkauft hatte. Der Fall wird jetzt vor dem Bundesgerichtshof in Karlsruhe verhandelt &#8211; als erstes Verfahren zu Gesch\u00e4ften dieser Art.<\/p>\n<p>Um 2005 litten Kommunen und mittelgro\u00dfe Unternehmen unter der Last hoher Realzinsen f\u00fcr ihre Kredite. Da empfohlen die Banken &#8211; in Deutschland voran die Deutsche Bank &#8211; CMS Spread Ladder Swaps. Dabei wetten die Kunden der Bank darauf, dass die kurzfristigen Zinsen in einem bestimmten Verh\u00e4ltnis zu den langfristigen Verh\u00e4ltnis fallen. Die Bank h\u00e4lt dagegen &#8211; und gewinnt unter anderem auch deshalb, weil sie, anders als die K\u00e4ufer der Swaps, die Vertr\u00e4ge k\u00fcndigen kann, wenn diese keine Gewinne mehr f\u00fcr die Bank abwerfen.<\/p>\n<p>In Deutschland f\u00fchrten die Gesch\u00e4fte zu Verlusten von mehreren hundert Millionen Euro\u00a0 in den St\u00e4dten Leipzig und Berlin, die Stadt Pforzheim verbuchte einen Verlust von 57 Millionen Euro. Auch in Italien wurden solche riskanten Wetten platziert &#8211; mit dem Ergebnis, dass italienische St\u00e4dte und Provinzen rund 2,5 Milliarden Euro an die Banken verloren. Da die &#8222;Kunden&#8220; nunmehr vor Gericht ziehen &#8211; inItalien mit dem Argument &#8222;vors\u00e4tzliche T\u00e4uschung&#8220; &#8211; reagieren die Banken zunehmend mit Gegenklagen auf &#8222;Vertragserf\u00fcllung&#8220; &#8211; meist vor Londoner Gerichten, die als bankenfreundlich bekannt sind.<\/p>\n<p><em>Quelle: taz 8.2.2011<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zwei Unternehmer werfen der Deutschen Bank Falschberatung vor, die ihnen Zinsswaps als &#8222;gutes Produkt zur Zinsoptimierung&#8220; verkauft hatte. Der Fall wird jetzt vor dem Bundesgerichtshof in Karlsruhe verhandelt &#8211; als erstes Verfahren zu Gesch\u00e4ften dieser Art. Um 2005 litten Kommunen und mittelgro\u00dfe Unternehmen unter der Last hoher Realzinsen f\u00fcr ihre Kredite. Da empfohlen die Banken [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[171,1028,42,293,244,572,1029],"class_list":["post-2068","post","type-post","status-publish","format-standard","hentry","category-casino","tag-banken","tag-cms","tag-deutsche-bank","tag-deutschland","tag-italien","tag-london","tag-spread-ladder-swaps"],"_links":{"self":[{"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/posts\/2068"}],"collection":[{"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/comments?post=2068"}],"version-history":[{"count":1,"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/posts\/2068\/revisions"}],"predecessor-version":[{"id":2069,"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/posts\/2068\/revisions\/2069"}],"wp:attachment":[{"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/media?parent=2068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/categories?post=2068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gegenstrom.net\/wordpress\/wp-json\/wp\/v2\/tags?post=2068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}